{"id":8233,"date":"2021-11-24T15:43:31","date_gmt":"2021-11-24T13:43:31","guid":{"rendered":"https:\/\/dtng.nl\/?p=8233"},"modified":"2023-07-10T20:35:36","modified_gmt":"2023-07-10T18:35:36","slug":"liefde-vroeger-eenvoudiger","status":"publish","type":"post","link":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/","title":{"rendered":"Was liefde vroeger echt eenvoudiger?"},"content":{"rendered":"\n<p><em>Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Uit cijfers blijkt dat er momenteel meer singles dan ooit zijn. In Amsterdam is meer dan 40% tussen de 20 en 40 vrijgezel. En dat terwijl opa en oma rond die leeftijd allang getrouwd waren. Dus vragen we ons af of de liefde vroeger niet eenvoudiger was? Dit lees je in onze blog!<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"1-niet-lullen-maar-poetsen\"><strong>1. Niet lullen maar poetsen<\/strong><\/h3>\n\n\n\n<p>Volgens psycholoog en schrijver van het boek&nbsp;<em>liefdesgedoe<\/em>&nbsp;Marcelino Lopez, was de liefde vroeger wel eenvoudiger. Een paar generaties geleden draaide een relatie niet om dezelfde passie hebben maar was het een praktische afspraak. Als je verlegen of sociaal onhandig was zorgden je ouders dat er iemand in je leven verscheen en na een paar keer seks hebben kwam er vaak al een baby. Daarna maakte je simpelweg gewoon het beste met elkaar ervan. Kortom, niet lullen maar poetsen.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-keuze-is-reuze\"><strong>2. Keuze is reuze<\/strong><\/h3>\n\n\n\n<p>Tegenwoordig is dat wel anders. \u201cLiefde is niet wat het was\u201d, volgens Marcelino. Waar liefde twee generaties geleden nog in een vissenkom ontstond, kunnen we tegenwoordig hengelen in de oceaan van het internet. De keuze is reuze en als er iets is waar het menselijk brein niet tegen kan, is het te veel keuze. Maar toch swipen en scrollen we er op los in de hoop die ideale match te vinden. We hebben tegenwoordig een waslijst aan criteria waar de perfecte partner aan moet voldoen. Maar een partner die aan al die criteria voldoet bestaat natuurlijk niet. Vroeger was de keuze eenvoudiger omdat er simpelweg niet veel keuze was en er was geen ruimte voor twijfel of spijt.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-gelukkig-zijn\"><strong>3. Gelukkig zijn<\/strong><\/h3>\n\n\n\n<p>We kunnen wel zeggen dat liefde vroeger eenvoudiger was. Maar betekent dat ook dat mensen vroeger gelukkiger waren? Onderzoek naar geluk is altijd een beetje lastig. Mensen hadden vroeger wel minder verwachtingen en waren daarom gewoon sneller tevreden. Mensen verwachten tegenwoordig meer van de liefde en we zijn pas tevreden als die verwachtingen overeenkomen met de werkelijkheid. De moderne tijd maakt mensen niet per se veel gelukkiger. Het maakt juist dat ze steeds verlangen en zoeken naar weer meer geluk, liefde en succes.<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-eisen\"><strong>4. Eisen<\/strong><\/h3>\n\n\n\n<p>We kunnen het ook van een andere kant gaan bekijken. Probeer bijvoorbeeld in plaats van te bedenken wat je niet hebt, eens stil te staan bij wat je wel hebt. Marcelino ziet het nog rooskleurig in: \u201cDoor de komst van online is het in ieder geval makkelijker dan ooit om met vrijgezellen in contact te komen. De grootste uitdaging is om je niet gek te laten maken. En niet al te hoge eisen in de liefde te hebben.\u201d<br><\/p>\n\n\n\n<p>Duss.. Stel je eisen bij en wees wat eerder tevreden, dan komt de liefde ook sneller!&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Uit cijfers blijkt dat er momenteel meer singles dan ooit zijn. In Amsterdam is meer dan 40% tussen de 20 en 40 vrijgezel. En dat terwijl opa en oma rond die leeftijd allang getrouwd waren. Dus vragen we ons af of de liefde vroeger niet [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":10015,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-8233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geen-onderdeel-van-een-categorie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was liefde vroeger echt eenvoudiger? - DTNG.<\/title>\n<meta name=\"description\" content=\"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was liefde vroeger echt eenvoudiger? - DTNG.\" \/>\n<meta property=\"og:description\" content=\"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/\" \/>\n<meta property=\"og:site_name\" content=\"DTNG.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dtng.matching\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-24T13:43:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-10T18:35:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Merel Nijman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Merel Nijman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/\"},\"author\":{\"name\":\"Merel Nijman\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#\\\/schema\\\/person\\\/c2ac409cc81c46d886856da7e01741c9\"},\"headline\":\"Was liefde vroeger echt eenvoudiger?\",\"datePublished\":\"2021-11-24T13:43:31+00:00\",\"dateModified\":\"2023-07-10T18:35:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/minpexels-cottonbro-studio-5934346-min-scaled.jpg\",\"articleSection\":[\"Geen onderdeel van een categorie\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/\",\"url\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/\",\"name\":\"Was liefde vroeger echt eenvoudiger? - DTNG.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/minpexels-cottonbro-studio-5934346-min-scaled.jpg\",\"datePublished\":\"2021-11-24T13:43:31+00:00\",\"dateModified\":\"2023-07-10T18:35:36+00:00\",\"description\":\"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/minpexels-cottonbro-studio-5934346-min-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/minpexels-cottonbro-studio-5934346-min-scaled.jpg\",\"width\":1706,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/liefde-vroeger-eenvoudiger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dtng.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was liefde vroeger echt eenvoudiger?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dtng.nl\\\/en\\\/\",\"name\":\"DTNG.\",\"description\":\"Relatiebemiddeling op maat voor hoogopgeleide vrijgezellen\",\"publisher\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dtng.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#organization\",\"name\":\"DTNG.\",\"url\":\"https:\\\/\\\/dtng.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/Logo-DTNG.png\",\"contentUrl\":\"https:\\\/\\\/dtng.nl\\\/wp-content\\\/uploads\\\/Logo-DTNG.png\",\"width\":700,\"height\":548,\"caption\":\"DTNG.\"},\"image\":{\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dtng.matching\\\/\",\"https:\\\/\\\/www.instagram.com\\\/dtngnl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dtng.nl\\\/en\\\/#\\\/schema\\\/person\\\/c2ac409cc81c46d886856da7e01741c9\",\"name\":\"Merel Nijman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g\",\"caption\":\"Merel Nijman\"},\"url\":\"https:\\\/\\\/dtng.nl\\\/en\\\/author\\\/merel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was liefde vroeger echt eenvoudiger? - DTNG.","description":"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/","og_locale":"en_US","og_type":"article","og_title":"Was liefde vroeger echt eenvoudiger? - DTNG.","og_description":"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.","og_url":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/","og_site_name":"DTNG.","article_publisher":"https:\/\/www.facebook.com\/dtng.matching\/","article_published_time":"2021-11-24T13:43:31+00:00","article_modified_time":"2023-07-10T18:35:36+00:00","og_image":[{"width":1706,"height":2560,"url":"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg","type":"image\/jpeg"}],"author":"Merel Nijman","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Merel Nijman","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#article","isPartOf":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/"},"author":{"name":"Merel Nijman","@id":"https:\/\/dtng.nl\/en\/#\/schema\/person\/c2ac409cc81c46d886856da7e01741c9"},"headline":"Was liefde vroeger echt eenvoudiger?","datePublished":"2021-11-24T13:43:31+00:00","dateModified":"2023-07-10T18:35:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/"},"wordCount":452,"publisher":{"@id":"https:\/\/dtng.nl\/en\/#organization"},"image":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#primaryimage"},"thumbnailUrl":"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg","articleSection":["Geen onderdeel van een categorie"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/","url":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/","name":"Was liefde vroeger echt eenvoudiger? - DTNG.","isPartOf":{"@id":"https:\/\/dtng.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#primaryimage"},"image":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#primaryimage"},"thumbnailUrl":"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg","datePublished":"2021-11-24T13:43:31+00:00","dateModified":"2023-07-10T18:35:36+00:00","description":"Het vinden van liefde is tegenwoordig niet meer zo eenvoudig. Was dit vroeger ook zo? Lees in deze blog of liefde vroeger eenvoudiger was.","breadcrumb":{"@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#primaryimage","url":"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg","contentUrl":"https:\/\/dtng.nl\/wp-content\/uploads\/minpexels-cottonbro-studio-5934346-min-scaled.jpg","width":1706,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/dtng.nl\/en\/liefde-vroeger-eenvoudiger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dtng.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Was liefde vroeger echt eenvoudiger?"}]},{"@type":"WebSite","@id":"https:\/\/dtng.nl\/en\/#website","url":"https:\/\/dtng.nl\/en\/","name":"DTNG.","description":"Relatiebemiddeling op maat voor hoogopgeleide vrijgezellen","publisher":{"@id":"https:\/\/dtng.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dtng.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dtng.nl\/en\/#organization","name":"DTNG.","url":"https:\/\/dtng.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dtng.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dtng.nl\/wp-content\/uploads\/Logo-DTNG.png","contentUrl":"https:\/\/dtng.nl\/wp-content\/uploads\/Logo-DTNG.png","width":700,"height":548,"caption":"DTNG."},"image":{"@id":"https:\/\/dtng.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dtng.matching\/","https:\/\/www.instagram.com\/dtngnl\/"]},{"@type":"Person","@id":"https:\/\/dtng.nl\/en\/#\/schema\/person\/c2ac409cc81c46d886856da7e01741c9","name":"Merel Nijman","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0374769d70cfc43006f166e6a24ef8ec2924dab6477ee6d418414229f3e70910?s=96&d=mm&r=g","caption":"Merel Nijman"},"url":"https:\/\/dtng.nl\/en\/author\/merel\/"}]}},"_links":{"self":[{"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/posts\/8233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/comments?post=8233"}],"version-history":[{"count":2,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/posts\/8233\/revisions"}],"predecessor-version":[{"id":10177,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/posts\/8233\/revisions\/10177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/media\/10015"}],"wp:attachment":[{"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/media?parent=8233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/categories?post=8233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dtng.nl\/en\/wp-json\/wp\/v2\/tags?post=8233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}